{"id":52843,"date":"2022-11-23T12:01:45","date_gmt":"2022-11-23T11:01:45","guid":{"rendered":"https:\/\/www.monjoc.com\/quadres-purpurina-onnanoko\/"},"modified":"2025-11-29T12:01:14","modified_gmt":"2025-11-29T11:01:14","slug":"quadres-purpurina-onnanoko","status":"publish","type":"product","link":"https:\/\/www.monjoc.com\/ca\/quadres-purpurina-onnanoko\/","title":{"rendered":"Purpurina &#8211; Onnanoko"},"content":{"rendered":"<p>Fes 4 quadres rodons amb dibuixos preciosos per a il\u00b7luminar amb purpurina i petits lluentons. El nen col\u00b7loca el seu quadre dins de la caixa, retira els pl\u00e0stics dels adhesius i despr\u00e9s col\u00b7loca els lluentons i posa la purpurina seguint el codi de colors que s&#8217;indica en el fullet.<br \/>\nPer a exposar les seves creacions, el nen pot col\u00b7locar els ganxos que s&#8217;inclouen per a penjar en la part posterior dels quadres.<br \/>\nQuin orgull admirar les nines que brillen amb tanta intensitat!<\/p>\n<p>-Una activitat neta: el nen treballa dins de la caixa per a evitar escampar la purpurina.<\/p>\n<p>-S&#8217;inclouen 4 ganxos adhesius per a penjar els quadres un cop acabats.<\/p>\n<p>Contingut: 4 l\u00e0mines impreses i amb adhesiu, de forma arrodonida (di\u00e0metre 21 cm), 4 tubs de purpurina, 1 joc de mini lluentons, 1 eina de pl\u00e0stic, 1 pinzell brotxa, 4 ganxos adhesius i 1 fullet\u00f3 explicatiu pas a pas a color.<\/p>\n<p>A partir de 6 anys<br \/>\nMides del producte: 21 x 21 cm<br \/>\nMides de la caixa: 24 x 23 x 4 cm<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fes 4 quadres rodons amb dibuixos preciosos per a il\u00b7luminar amb purpurina i petits lluentons. El nen col\u00b7loca el seu quadre dins de la caixa, retira els pl\u00e0stics dels adhesius i despr\u00e9s col\u00b7loca els lluentons i posa la purpurina seguint el codi de colors que s&#8217;indica en el fullet.<\/p>\n","protected":false},"featured_media":53553,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[931,932,169,78,99],"product_tag":[],"giftcard-category":[],"class_list":["post-52843","product","type-product","status-publish","has-post-thumbnail","product_cat-5-a-6-anys","product_cat-7-a-8-anys","product_cat-art","product_cat-djeco","product_cat-mes-de-8-anys","pa_edat-recomenada-a-partir-de-6-anys","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Purpurina - Onnanoko - Monjoc<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.monjoc.com\/ca\/quadres-purpurina-onnanoko\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Purpurina - Onnanoko - Monjoc\" \/>\n<meta property=\"og:description\" content=\"Fes 4 quadres rodons amb dibuixos preciosos per a il\u00b7luminar amb purpurina i petits lluentons. El nen col\u00b7loca el seu quadre dins de la caixa, retira els pl\u00e0stics dels adhesius i despr\u00e9s col\u00b7loca els lluentons i posa la purpurina seguint el codi de colors que s&#039;indica en el fullet.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.monjoc.com\/ca\/quadres-purpurina-onnanoko\/\" \/>\n<meta property=\"og:site_name\" content=\"Monjoc\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/monjoc.labisbal\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-29T11:01:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.monjoc.com\/wp-content\/uploads\/2022\/11\/TOPT.3070900095236-principal.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.monjoc.com\\\/ca\\\/quadres-purpurina-onnanoko\\\/\",\"url\":\"https:\\\/\\\/www.monjoc.com\\\/ca\\\/quadres-purpurina-onnanoko\\\/\",\"name\":\"Purpurina - Onnanoko - Monjoc\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.monjoc.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.monjoc.com\\\/ca\\\/quadres-purpurina-onnanoko\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.monjoc.com\\\/ca\\\/quadres-purpurina-onnanoko\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.monjoc.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/TOPT.3070900095236-principal.jpg\",\"datePublished\":\"2022-11-23T11:01:45+00:00\",\"dateModified\":\"2025-11-29T11:01:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.monjoc.com\\\/ca\\\/quadres-purpurina-onnanoko\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.monjoc.com\\\/ca\\\/quadres-purpurina-onnanoko\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.monjoc.com\\\/ca\\\/quadres-purpurina-onnanoko\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.monjoc.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/TOPT.3070900095236-principal.jpg\",\"contentUrl\":\"https:\\\/\\\/www.monjoc.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/TOPT.3070900095236-principal.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.monjoc.com\\\/ca\\\/quadres-purpurina-onnanoko\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.monjoc.com\\\/ca\\\/home-monjoc-botiga-de-joguines-a-la-bisbal-demporda\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Purpurina &#8211; Onnanoko\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.monjoc.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.monjoc.com\\\/ca\\\/\",\"name\":\"Monjoc\",\"description\":\"Botiga de Joguines i Jocs Educatius La Bisbal d&#039;Empord\u00e0\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.monjoc.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Purpurina - Onnanoko - Monjoc","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.monjoc.com\/ca\/quadres-purpurina-onnanoko\/","og_locale":"ca_ES","og_type":"article","og_title":"Purpurina - Onnanoko - Monjoc","og_description":"Fes 4 quadres rodons amb dibuixos preciosos per a il\u00b7luminar amb purpurina i petits lluentons. El nen col\u00b7loca el seu quadre dins de la caixa, retira els pl\u00e0stics dels adhesius i despr\u00e9s col\u00b7loca els lluentons i posa la purpurina seguint el codi de colors que s'indica en el fullet.","og_url":"https:\/\/www.monjoc.com\/ca\/quadres-purpurina-onnanoko\/","og_site_name":"Monjoc","article_publisher":"https:\/\/www.facebook.com\/monjoc.labisbal","article_modified_time":"2025-11-29T11:01:14+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.monjoc.com\/wp-content\/uploads\/2022\/11\/TOPT.3070900095236-principal.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.monjoc.com\/ca\/quadres-purpurina-onnanoko\/","url":"https:\/\/www.monjoc.com\/ca\/quadres-purpurina-onnanoko\/","name":"Purpurina - Onnanoko - Monjoc","isPartOf":{"@id":"https:\/\/www.monjoc.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.monjoc.com\/ca\/quadres-purpurina-onnanoko\/#primaryimage"},"image":{"@id":"https:\/\/www.monjoc.com\/ca\/quadres-purpurina-onnanoko\/#primaryimage"},"thumbnailUrl":"https:\/\/www.monjoc.com\/wp-content\/uploads\/2022\/11\/TOPT.3070900095236-principal.jpg","datePublished":"2022-11-23T11:01:45+00:00","dateModified":"2025-11-29T11:01:14+00:00","breadcrumb":{"@id":"https:\/\/www.monjoc.com\/ca\/quadres-purpurina-onnanoko\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.monjoc.com\/ca\/quadres-purpurina-onnanoko\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.monjoc.com\/ca\/quadres-purpurina-onnanoko\/#primaryimage","url":"https:\/\/www.monjoc.com\/wp-content\/uploads\/2022\/11\/TOPT.3070900095236-principal.jpg","contentUrl":"https:\/\/www.monjoc.com\/wp-content\/uploads\/2022\/11\/TOPT.3070900095236-principal.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.monjoc.com\/ca\/quadres-purpurina-onnanoko\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.monjoc.com\/ca\/home-monjoc-botiga-de-joguines-a-la-bisbal-demporda\/"},{"@type":"ListItem","position":2,"name":"Purpurina &#8211; Onnanoko"}]},{"@type":"WebSite","@id":"https:\/\/www.monjoc.com\/ca\/#website","url":"https:\/\/www.monjoc.com\/ca\/","name":"Monjoc","description":"Botiga de Joguines i Jocs Educatius La Bisbal d&#039;Empord\u00e0","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.monjoc.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"}]}},"_links":{"self":[{"href":"https:\/\/www.monjoc.com\/ca\/wp-json\/wp\/v2\/product\/52843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.monjoc.com\/ca\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.monjoc.com\/ca\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.monjoc.com\/ca\/wp-json\/wp\/v2\/comments?post=52843"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.monjoc.com\/ca\/wp-json\/wp\/v2\/media\/53553"}],"wp:attachment":[{"href":"https:\/\/www.monjoc.com\/ca\/wp-json\/wp\/v2\/media?parent=52843"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.monjoc.com\/ca\/wp-json\/wp\/v2\/product_brand?post=52843"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.monjoc.com\/ca\/wp-json\/wp\/v2\/product_cat?post=52843"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.monjoc.com\/ca\/wp-json\/wp\/v2\/product_tag?post=52843"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/www.monjoc.com\/ca\/wp-json\/wp\/v2\/giftcard-category?post=52843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}